{"id":3,"date":"2024-08-28T16:16:42","date_gmt":"2024-08-28T16:16:42","guid":{"rendered":"https:\/\/rayocredit.com\/cr\/?page_id=3"},"modified":"2025-06-09T19:07:27","modified_gmt":"2025-06-10T01:07:27","slug":"politica-de-tratamiento-de-datos-rayo-costa-rica","status":"publish","type":"page","link":"https:\/\/rayocredit.com\/cr\/politica-de-tratamiento-de-datos-rayo-costa-rica\/","title":{"rendered":"Pol\u00edtica de Tratamiento de Datos Rayo Costa Rica"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/rayocredit.com\/cr\/acerca\/\" title=\"Acerca\"  data-wpil-monitor-id=\"139\">Rayo<\/a>CR S.A.&nbsp;<\/strong>(en adelante&nbsp;<strong>\u201cRAYO\u201d<\/strong>) es una sociedad costarricense identificada con el Ceb Jur\u00eddico n\u00famero 3-101-673923, cuyo domicilio es Avenida 1era calle 7, edificio Omni, local Rayo, San Jos\u00e9, Costa Rica.<\/p>\n\n\n\n<p>En cumplimiento de lo dictado en Ley N\u00ba 8968 del 2011 de la Constituci\u00f3n Pol\u00edtica y sus decretos reglamentarios se informa que&nbsp;<strong>RAYO<\/strong>&nbsp;es Responsable del Tratamiento de los Datos Personales que recolecta y para ello cuenta con la siguiente Pol\u00edtica de Tratamiento de Datos Personales.<\/p>\n\n\n\n<p>Los mecanismos a trav\u00e9s de los cuales&nbsp;<strong>RAYO<\/strong>&nbsp;hace uso de tus datos personales son seguros y privados, ya que contamos con los medios f\u00edsicos y tecnol\u00f3gicos id\u00f3neos para asegurar que son tratados de manera tal que se impida el acceso indeseado o no autorizado por parte de terceras personas y, en ese mismo sentido, asegurar la privacidad de los mismos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I. Definiciones<\/h3>\n\n\n\n<p>Para efectos de la presente pol\u00edtica, los t\u00e9rminos que se se\u00f1alan a continuaci\u00f3n tendr\u00e1n los siguientes significados, de acuerdo con lo establecido en la Ley 8968 del 2011 y sus respectivos decretos reglamentarios:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Base de datos: cualquier archivo, fichero, registro u otro conjunto estructurado de datos personales, que sean objeto de tratamiento o procesamiento, automatizado o manuales, cualquiera que sea la modalidad de su elaboraci\u00f3n, organizaci\u00f3n o acceso.<\/li>\n\n\n\n<li>Datos personales: cualquier dato relativo a una persona f\u00edsica identificada o identificable.<\/li>\n\n\n\n<li>Datos personales de acceso irrestricto: los contenidos en bases de datos p\u00fablicas de acceso general, seg\u00fan dispongan leyes especiales y de conformidad con la finalidad para la cual estos datos fueron recabados.<\/li>\n\n\n\n<li>Datos personales de acceso restringido: los que, aun formando parte de registros de acceso al p\u00fablico, no son de acceso irrestricto por ser de inter\u00e9s solo para su titular o para la Administraci\u00f3n P\u00fablica.<\/li>\n\n\n\n<li>Datos sensibles: informaci\u00f3n relativa al fuero \u00edntimo de la persona, como por ejemplo los que revelen origen racial, opiniones pol\u00edticas, convicciones religiosas o espirituales, condici\u00f3n socioecon\u00f3mica, informaci\u00f3n biom\u00e9dica o gen\u00e9tica, vida y orientaci\u00f3n sexual, entre otros.<\/li>\n\n\n\n<li>Deber de confidencialidad: obligaci\u00f3n de los responsables de bases de datos, personal a su cargo y del personal de la Agencia de Protecci\u00f3n de Datos de los Habitantes (Prodhab), de guardar la confidencialidad con ocasi\u00f3n del ejercicio de las facultades dadas por esta ley, principalmente cuando se acceda a informaci\u00f3n sobre datos personales y sensibles. Esta obligaci\u00f3n perdurar\u00e1 aun despu\u00e9s de finalizada la relaci\u00f3n con la base de datos.<\/li>\n\n\n\n<li>Interesado: persona f\u00edsica, titular de los datos que sean objeto del tratamiento automatizado o manual.<\/li>\n\n\n\n<li>Responsable de la base de datos: persona f\u00edsica o jur\u00eddica que administre, gerencia o se encargue de la base de datos, ya sea esta una entidad p\u00fablica o privada, competente, con arreglo a la ley, para decidir cu\u00e1l es la finalidad de la base de datos, cu\u00e1les categor\u00edas de datos de car\u00e1cter personal deber\u00e1n registrase y qu\u00e9 tipo de tratamiento se les aplicar\u00e1n.<\/li>\n\n\n\n<li>Tratamiento de datos personales: cualquier operaci\u00f3n o conjunto de operaciones, efectuadas mediante procedimientos automatizados o manuales y aplicadas a datos personales, tales como la recolecci\u00f3n, el registro, la organizaci\u00f3n, la conservaci\u00f3n, la modificaci\u00f3n, la extracci\u00f3n, la consulta, la utilizaci\u00f3n, la comunicaci\u00f3n por transmisi\u00f3n, difusi\u00f3n o cualquier otra forma que facilite el acceso a estos, el cotejo o la interconexi\u00f3n, as\u00ed como su bloqueo, supresi\u00f3n o destrucci\u00f3n, entre otros.<\/li>\n<\/ol>\n\n\n\n<p>En el ejercicio de sus atribuciones, la Prodhab deber\u00e1 emplear procedimientos automatizados, de acuerdo con las mejores herramientas tecnol\u00f3gicas a su alcance.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">II. Avisos legales<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>El&nbsp;<strong>USUARIO<\/strong>&nbsp;declara y se obliga a que sus conductas se ajusten a la ley, implementando toda medida que evite que sus operaciones con&nbsp;<strong>RAYO<\/strong>&nbsp;sean con o sin su consentimiento y conocimiento como instrumento para el ocultamiento, manejo, defraudaci\u00f3n o aprovechamiento en cualquier forma de la identidad.<\/li>\n\n\n\n<li>El&nbsp;<strong>USUARIO<\/strong>&nbsp;ser\u00e1 responsable frente a&nbsp;<strong>RAYO<\/strong>&nbsp;por todos los perjuicios que se causaren como consecuencia de incumplir las declaraciones y obligaci\u00f3n anteriores. Dicha responsabilidad se extender\u00e1 a terceros.<\/li>\n\n\n\n<li>Al acceder a la p\u00e1gina web el&nbsp;<strong>USUARIO<\/strong>&nbsp;declara que es mayor de edad y dispone de la capacidad necesaria para contratar con&nbsp;<strong>RAYO<\/strong>, manifiesta que entiende y acepta en totalidad las condiciones aqu\u00ed enunciadas para utilizaci\u00f3n de la p\u00e1gina web y la contrataci\u00f3n con&nbsp;<strong>RAYO<\/strong>.<\/li>\n\n\n\n<li>El&nbsp;<strong>USUARIO<\/strong>&nbsp;acepta que el acceso a la pagina web, as\u00ed como el uso que pueda hacer de los servicios e informaci\u00f3n contenida en la misma, son de exclusiva responsabilidad del&nbsp;<strong>USUARIO<\/strong>.<\/li>\n\n\n\n<li><strong>RAYO<\/strong>&nbsp;no ser\u00e1 responsable por los errores que llegase a presentar la informaci\u00f3n que no sea de su autor\u00eda.&nbsp;<strong>RAYO<\/strong>&nbsp;tampoco ser\u00e1 responsable de los da\u00f1os o perjuicios que se puedan llegar a ocasionar como resultado del uso de dicha informaci\u00f3n.<\/li>\n\n\n\n<li><strong>RAYO<\/strong>&nbsp;podr\u00e1 guardar registros f\u00edsicos o magn\u00e9ticos con el fin de comprobar la identidad y la veracidad de los datos indicados por el USUARIO.<\/li>\n\n\n\n<li><strong>RAYO<\/strong>&nbsp;presumir\u00e1 que, si el&nbsp;<strong>USUARIO<\/strong>&nbsp;est\u00e1 actuando a nombre una persona jur\u00eddica con o sin \u00e1nimo de lucro, es porque est\u00e1 en la total capacidad y autorizaci\u00f3n de hacerlo.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">III. Uso de la informaci\u00f3n personal<\/h3>\n\n\n\n<p>Esta pol\u00edtica es aplicable a los datos personales que los Titulares de la informaci\u00f3n directamente o Terceros autorizados entregan a RAYO por cualquier medio (verbal, pagina web o f\u00edsico), y para aquellos que, a trav\u00e9s de cualquier medio licito, sean recaudados por RAYO sin requerir de una autorizaci\u00f3n previa para su tratamiento.<\/p>\n\n\n\n<p>1. Tratamiento de datos p\u00fablicos<\/p>\n\n\n\n<p>Es posible que&nbsp;<strong>RAYO<\/strong>&nbsp;realice el Tratamiento de datos personales de naturaleza p\u00fablica sin previa autorizaci\u00f3n de los Titulares, recopilados \u00e9stos de registros p\u00fablicos, documentos p\u00fablicos, gacetas, boletines oficiales y\/o sentencias judiciales debidamente ejecutoriadas.<\/p>\n\n\n\n<p>Esta situaci\u00f3n no implica que no se adopten las medidas necesarias que garanticen el cumplimiento de los principios y obligaciones contempladas en la Ley 8968 de 2011 y sus decretos reglamentarios.<\/p>\n\n\n\n<p>2. Tratamiento de informaci\u00f3n personal de funcionarios<\/p>\n\n\n\n<p>A trav\u00e9s de los diferentes canales de comunicaci\u00f3n o de los documentos dispuestos para el efecto, por medio los cuales se realiza el proceso de selecci\u00f3n y posteriormente se formaliza la vinculaci\u00f3n laboral, se recolectan y almacenan datos personales de los funcionarios de&nbsp;<strong>RAYO.<\/strong><\/p>\n\n\n\n<p>Esta informaci\u00f3n es entregada directamente por los Titulares de la informaci\u00f3n o recopilada mediante fuentes p\u00fablicas o privadas, estas \u00faltimas consultadas previa autorizaci\u00f3n del titular, y es tratada conforme la presente Pol\u00edtica, dentro del marco contextual de la Ley 8968 de 2011 y normas reglamentarias, y bajo las finalidades consagradas en las autorizaciones otorgadas para el efecto.<\/p>\n\n\n\n<p>3. Tratamiento de informaci\u00f3n personal de proveedores y contratistas<\/p>\n\n\n\n<p>A trav\u00e9s de los diferentes canales de comunicaci\u00f3n o de los documentos dispuestos para el efecto, por medio los cuales se formaliza la vinculaci\u00f3n de proveedores y contratistas, se recolectan y almacenan datos personales de los proveedores que prestan sus servicios a&nbsp;<strong>RAYO.<\/strong><\/p>\n\n\n\n<p>Esta informaci\u00f3n es entregada directamente por el representante legal del proveedor, en caso de encontrarse constituido como una persona jur\u00eddica, y\/o directamente por los Titulares de la informaci\u00f3n, y es tratada conforme la presente Pol\u00edtica, dentro del marco contextual de la Ley 8968 de 2011 y normas reglamentarias, y bajo las finalidades consagradas en las autorizaciones otorgadas para el efecto.<\/p>\n\n\n\n<p>4. Tratamiento de informaci\u00f3n personal de los solicitantes de servicios y clientes<\/p>\n\n\n\n<p>Mediante diferentes herramientas tecnol\u00f3gicas, canales de comunicaci\u00f3n y\/o documentos dispuestos para la vinculaci\u00f3n de los&nbsp;<strong>USUARIOS<\/strong>&nbsp;de&nbsp;<strong>RAYO<\/strong>, y en el normal desarrollo de sus operaciones, recolecta, almacena y en general realiza el tratamiento de los datos personales de quienes solicitan los servicios de RAYO, as\u00ed como de quienes se convierten en clientes, entregados \u00e9stos directamente por los Titulares de la informaci\u00f3n, y es tratada, conforme a la presente Pol\u00edtica, dentro del marco contextual de la Ley 8968 de 2011 y normas reglamentarias, y bajo las finalidades consagradas en las autorizaciones otorgadas para el efecto.<\/p>\n\n\n\n<p>5. Tratamiento de informaci\u00f3n personal sensible<\/p>\n\n\n\n<p>En desarrollo de sus actividades&nbsp;<strong>RAYO<\/strong>&nbsp;no recopila, almacena o trata datos que se puedan considerar sensibles y que no resulten adecuados para sus labores comerciales. No obstante, en caso de requerirse este tipo de informaci\u00f3n para el adecuado desarrollo de sus actividades o la prestaci\u00f3n de sus servicios, RAYO solicita a los Titulares su autorizaci\u00f3n expresa, previa e informada, la cual siempre se brinda de manera libre y voluntaria.<\/p>\n\n\n\n<p>Las respuestas a las preguntas que sean efectuadas a los Titulares en torno a informaci\u00f3n sensible ser\u00e1n facultativas y en este caso se informar\u00e1 previamente al Titular que informaci\u00f3n sensible se est\u00e1 recolectando y las razones del tratamiento realizado por parte de&nbsp;<strong>RAYO<\/strong>.<\/p>\n\n\n\n<p>6. Tratamiento de informaci\u00f3n personal de usuarios de las plataformas digitales<\/p>\n\n\n\n<p>A trav\u00e9s de los diferentes sitios web y\/o aplicaciones propias de RAYO, se recolecta, almacena y en general se realiza el tratamiento de los datos personales de quienes acceden a estas herramientas digitales y se registran mediante los accesos \u201cMi cuenta\u201d o \u201cQuieres mas informaci\u00f3n\u201d o dem\u00e1s accesos y que sean entregados directamente por los Titulares de la informaci\u00f3n. Esta informaci\u00f3n es tratada conforme a la presente Pol\u00edtica, dentro del marco contextual de la Ley 1581 de 2012 y normas reglamentarias, y bajo las finalidades consagradas en las autorizaciones otorgadas para el efecto.<\/p>\n\n\n\n<p>As\u00ed mismo, nuestros sitios web y\/o aplicaciones permiten en muchas ocasiones compartir im\u00e1genes, fotograf\u00edas, comentarios, art\u00edculos y blogs. Al subir este contenido se autoriza a&nbsp;<strong>RAYO<\/strong>&nbsp;para presentarlo en su p\u00e1gina de internet, redes sociales u otros medios de comunicaci\u00f3n y utilizarlos como parte de campa\u00f1as comerciales o de mercadeo dirigidas al p\u00fablico en general a trav\u00e9s de distintos medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p>7. Seguridad y filmaciones (grabaciones)<\/p>\n\n\n\n<p><strong>RAYO<\/strong>&nbsp;como parte de sus pol\u00edticas de seguridad, monitoreo de sus actividades y controles de entrada y salida de sus oficinas, podr\u00e1 realizar grabaciones de audio y video en sus oficinas y sitios comunes de sus instalaciones. Tales grabaciones realizadas mediante un sistema de video vigilancia, tendr\u00e1n una duraci\u00f3n en los archivos de la entidad de un m\u00e1ximo de dos a\u00f1os para posteriormente ser objeto de borrado o destrucci\u00f3n segura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">IV. Terceros y la informaci\u00f3n personal<\/h3>\n\n\n\n<p>1. Encargados del tratamiento de la informaci\u00f3n<\/p>\n\n\n\n<p>Como se establece en las finalidades con las cuales se recolecta y trata la informaci\u00f3n personal,&nbsp;<strong>RAYO<\/strong>, para la adecuada prestaci\u00f3n de sus servicios, acudir\u00e1 en ocasiones a personas naturales o jur\u00eddicas para que con su colaboraci\u00f3n se puedan realizar adecuadamente todas las labores y se preste el mejor servicio a sus funcionarios, usuarios, clientes, proveedores y\/o contratistas.<\/p>\n\n\n\n<p>Esto implicar\u00e1 que en ocasiones exista la necesidad de que esos terceros tengan acceso a determinada informaci\u00f3n personal almacenada en las bases de datos de&nbsp;<strong>RAYO<\/strong>, caso en el cual se velar\u00e1 porque:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Toda informaci\u00f3n que se entregue a un tercero estar\u00e1 precedida de un acuerdo en donde consten sus obligaciones de confidencialidad y seguridad en el tratamiento de la informaci\u00f3n, las cuales ser\u00e1n, al menos similares a las establecidas por&nbsp;<strong>RAYO<\/strong>&nbsp;en sus procesos internos.<\/li>\n\n\n\n<li>b. La informaci\u00f3n s\u00f3lo sea utilizada para el cumplimiento de las finalidades establecidas en las autorizaciones otorgadas por los titulares y en esta pol\u00edtica de privacidad.<\/li>\n\n\n\n<li>c. S\u00f3lo se comparta la informaci\u00f3n estrictamente necesaria para el cumplimiento de las funciones del tercero encomendadas por&nbsp;<strong>RAYO<\/strong>.<\/li>\n\n\n\n<li>d. La informaci\u00f3n compartida con un tercero ser\u00e1 devuelta por \u00e9ste a&nbsp;<strong>RAYO<\/strong>&nbsp;o destruida de forma segura en caso de no ser posible la devoluci\u00f3n, una vez el tercero haya desarrollado las labores encargadas.<\/li>\n<\/ol>\n\n\n\n<p>2. Informaci\u00f3n personal proveniente de terceros<\/p>\n\n\n\n<p>En desarrollo de alianzas de tipo comercial dentro de las que se incluye el ofrecimiento de los productos o servicio de&nbsp;<strong>RAYO<\/strong>&nbsp;por parte de terceros, o el ofrecimiento de productos y servicios de terceros por parte de&nbsp;<strong>RAYO<\/strong>, previo acuerdo para el efecto, se podr\u00e1 recibir informaci\u00f3n personal recopilada de forma independiente por dichos terceros.<\/p>\n\n\n\n<p>En estos casos&nbsp;<strong>RAYO<\/strong>&nbsp;actuar\u00e1 como Encargado del tratamiento de la informaci\u00f3n, de tal manera que su actuaci\u00f3n siempre estar\u00e1 basada en el convencimiento que esos terceros cuentan con las autorizaciones necesarias para utilizar la informaci\u00f3n con las finalidades para la cuales es entregada a la entidad.<\/p>\n\n\n\n<p>En caso de ejercicio de los derechos por parte del Titular de los datos personales suministrados por el tercero,&nbsp;<strong>RAYO<\/strong>&nbsp;har\u00e1 sus mejores esfuerzos por realizar el traslado de la solicitud a los Responsables correspondientes y porque se brinde una respuesta adecuada a las necesidades del peticionario sin hacerse responsable por el tratamiento de los datos efectuado por el tercero, el alcance de las autorizaciones otorgadas, ni por el contenido de las respuestas que se den a las solicitudes.<\/p>\n\n\n\n<p>3. Informaci\u00f3n personal de referencias<\/p>\n\n\n\n<p>La recepci\u00f3n de la informaci\u00f3n personal de terceras personas entregada por los clientes, usuarios solicitantes de servicios, proveedores o funcionarios de&nbsp;<strong>RAYO<\/strong>&nbsp;debe estar precedida de las debidas autorizaciones por parte de los Titulares de la informaci\u00f3n.<\/p>\n\n\n\n<p>De esta manera,&nbsp;<strong>RAYO<\/strong>&nbsp;entiende que quien realiza entrega de informaci\u00f3n personal correspondiente a terceros, como es el caso de la entrega de personas que sirven de referencia personal o comercial, cuenta con todas las autorizaciones pertinentes para su tratamiento y en ese sentido libera a&nbsp;<strong>RAYO<\/strong>&nbsp;de cualquier responsabilidad por el uso que le d\u00e9 a los datos personales de acuerdo con las finalidades para las cuales se le hace entrega de la informaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">V. Finalidades del tratamiento de la informaci\u00f3n personal<\/h3>\n\n\n\n<p><strong>RAYO<\/strong>&nbsp;realiza el Tratamiento de la informaci\u00f3n personal con el principal objetivo de cumplir con sus objeto, actuando siempre de acuerdo a la presente Pol\u00edtica y a lo dispuesto las autorizaciones otorgadas de forma previa y expresa por los Titulares de la informaci\u00f3n.<\/p>\n\n\n\n<p>La informaci\u00f3n personal ser\u00e1 tratada por RAYO de acuerdo con las siguientes finalidades:<\/p>\n\n\n\n<p>1. Informaci\u00f3n personal de funcionarios<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Realizar procesos de selecci\u00f3n.<\/li>\n\n\n\n<li>b. Verificar datos de estudio, experiencia laboral y referencias laborales y personales mediante fuentes p\u00fablicas y\/o privadas<\/li>\n\n\n\n<li>c. Realizar pruebas psicot\u00e9cnicas, estudios de seguridad y ex\u00e1menes m\u00e9dicos<\/li>\n\n\n\n<li>d. Realizar todas las actividades relativas a la vinculaci\u00f3n de personal y manejo de relaciones laborales<\/li>\n\n\n\n<li>e. Realizar las respectivas investigaciones administrativas y\/o disciplinarias a las que haya lugar tomando como insumo las grabaciones de seguridad tomadas por el sistema de video vigilancia propio de&nbsp;<strong>RAYO<\/strong><\/li>\n\n\n\n<li>f. Cumplimiento de obligaciones legales en materia de afiliaciones al sistema de seguridad sociales y archivo de informaci\u00f3n<\/li>\n<\/ol>\n\n\n\n<p>2. Informaci\u00f3n personal de proveedores<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Realizar todas las actividades relativas a la selecci\u00f3n, contrataci\u00f3n y evaluaci\u00f3n de proveedores<\/li>\n\n\n\n<li>b. Verificar la viabilidad financiera, jur\u00eddica y comercial de una eventual relaci\u00f3n comercial<\/li>\n\n\n\n<li>c. Verificar la informaci\u00f3n suministrada por los proveedores, potenciales y\/o contratados, ante centrales de riesgo, fuentes privadas y\/o p\u00fablicas, y dem\u00e1s listas que se considere pertinente para acreditar la experiencia indicada<\/li>\n\n\n\n<li>d. Ejecutar y\/o dar cumplimiento a obligaciones derivadas de los contractos y\/o acuerdos comerciales suscritos<\/li>\n<\/ol>\n\n\n\n<p>3. Informaci\u00f3n personal de usuarios de plataformas digitales y solicitantes de servicios<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Efectuar el registro e identificaci\u00f3n como usuario de las plataformas virtuales de RAYO<\/li>\n\n\n\n<li>b. Enviar comunicaciones con informaci\u00f3n considerada de inter\u00e9s de los usuarios y solicitantes de servicios y\/o relacionada con los servicios y productos de RAYO y\/o de terceros con los que se tengan relaciones comerciales o alianzas, con fines comerciales y de mercadeo, a trav\u00e9s de correos electr\u00f3nicos, mensajes de texto (SMS\/MMS), herramientas de conversaci\u00f3n instant\u00e1nea, comunicaci\u00f3n telef\u00f3nica y\/o por cualquier otro medio de contacto conocido o que llegue a desarrollarse en un futuro<\/li>\n\n\n\n<li>c. Realizar consultas ante los operadores de informaci\u00f3n con el fin de realizar un an\u00e1lisis de tu perfil comercial, laboral y financiero, de forma tal que podamos estudiar la viabilidad de iniciar o mantener una relaci\u00f3n comercial con los usuarios que realicen solicitudes de servicios;<\/li>\n\n\n\n<li>d. Dar tr\u00e1mite a las solicitudes de servicios efectuadas por los usuarios de las plataformas digitales<\/li>\n\n\n\n<li>e. Realizar gesti\u00f3n de conocimiento y validaci\u00f3n de los datos suministrados por medio de los formularios dispuestos para el registro y solicitud de servicios en fuentes p\u00fablicas y privadas, as\u00ed como mediante comunicaci\u00f3n con quienes son registrados como referencias;<\/li>\n\n\n\n<li>f. Procesar la informaci\u00f3n con el fin de realizar actividades de prospecci\u00f3n, segmentaci\u00f3n y conocimiento de usuarios, solicitantes de servicios y clientes<\/li>\n<\/ol>\n\n\n\n<p>4. Informaci\u00f3n personal de clientes<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Efectuar el registro e identificaci\u00f3n como cliente de&nbsp;<strong>RAYO<\/strong><\/li>\n\n\n\n<li>b. Realizar ante los Operadores de Informaci\u00f3n (Datacr\u00e9dito (Experian), Cifin (Transunion) y\/o cualquier otra entidad que llegue a manejar bases de datos con los mismos objetivos) la consulta de la informaci\u00f3n crediticia, as\u00ed como el reporte de la generaci\u00f3n, modificaci\u00f3n, extinci\u00f3n, cumplimiento o incumplimiento de las obligaciones contra\u00eddas en favor de&nbsp;<strong>RAYO<\/strong>&nbsp;y la utilizaci\u00f3n indebida de los productos y\/o servicios prestados u ofrecidos por la entidad<\/li>\n\n\n\n<li>c. Realizar gesti\u00f3n de conocimiento y validaci\u00f3n de los datos suministrados por medio de los formularios dispuestos para el registro y solicitud de servicios en fuentes p\u00fablicas y privadas, as\u00ed como mediante comunicaci\u00f3n con quienes son registrados como referencias;<\/li>\n\n\n\n<li>d. Gestionar los servicios ofrecidos por&nbsp;<strong>RAYO<\/strong>&nbsp;a trav\u00e9s de sus p\u00e1ginas web, aplicaciones m\u00f3viles y cualquier otra plataforma tecnol\u00f3gica desarrollada por la entidad, realizando validaci\u00f3n biom\u00e9trica o conocimiento de la geolocalizaci\u00f3n del usuario o cliente cuando as\u00ed lo establezca&nbsp;<strong>RAYO<\/strong>&nbsp;para la prestaci\u00f3n de sus servicios.<\/li>\n\n\n\n<li>e. Compartir e intercambiar con sus entidades filiales, matrices, aliadas y\/o con entidades financieras, dentro y fuera del territorio colombiano, la informaci\u00f3n personal contenida en las bases de datos con fines de control de riesgos, desembolso y pago de obligaciones, comerciales, estad\u00edsticos y la realizaci\u00f3n de actividades de mercadeo y publicidad de sus servicios<\/li>\n\n\n\n<li>f. Utilizar los comentarios, art\u00edculos, im\u00e1genes u otros contenidos publicados por los clientes o usuarios en nuestras p\u00e1ginas de internet, redes sociales y en cualquier otra que llegue a ser creada o usada por la entidad, para la realizaci\u00f3n de actividades comerciales o de mercadeo de RAYO a trav\u00e9s de nuestras p\u00e1ginas de internet, redes sociales u otros medios de comunicaci\u00f3n conocidos o por conocer, as\u00ed como utilizarlos como parte de nuestras campa\u00f1as comerciales o de mercadeo dirigidas al p\u00fablico en general a trav\u00e9s de distintos medios de comunicaci\u00f3n<\/li>\n\n\n\n<li>g. Adelantar contacto y enviar comunicaciones con informaci\u00f3n considerada de inter\u00e9s de los clientes y\/o relacionada con los servicios y productos de&nbsp;<strong>RAYO<\/strong>&nbsp;y\/o de terceros con los que se tengan relaciones comerciales o alianzas, con fines comerciales y de mercadeo, a trav\u00e9s de correos electr\u00f3nicos, mensajes de texto (SMS\/MMS), herramientas de conversaci\u00f3n instant\u00e1nea, comunicaci\u00f3n telef\u00f3nica y\/o por cualquier otro medio de contacto conocido o que llegue a desarrollarse en un futuro<\/li>\n\n\n\n<li>h. Realizar actividades de cobranza, aviso de reporte a las centrales de riesgo, entrega de extractos y paz y salvo de obligaciones por cualquier medio de comunicaci\u00f3n, ya sea este correo electr\u00f3nico, mensaje de texto (SMS\/MMS), herramientas de conversaci\u00f3n instant\u00e1nea, tel\u00e9fono y\/o por cualquier otro medio de contacto conocido o que llegue a desarrollarse en un futuro<\/li>\n\n\n\n<li>i. Realizar gesti\u00f3n de conocimiento y actualizaci\u00f3n de la informaci\u00f3n personal de los clientes a trav\u00e9s de diferentes actividades como lo son la consulta en bases de datos p\u00fablicas, p\u00e1ginas de internet, redes sociales y por medio de contacto con las personas que han servido de referencia para la aprobaci\u00f3n y utilizaci\u00f3n de los servicios de&nbsp;<strong>RAYO<\/strong><\/li>\n\n\n\n<li>j. Compartir la informaci\u00f3n personal recopilada por&nbsp;<strong>RAYO<\/strong>&nbsp;con terceros proveedores localizados en Colombia o en el exterior para las mismas finalidades se\u00f1aladas en la presente pol\u00edtica y en las correspondientes autorizaciones. Para efectos de esta finalidad, se tiene como terceros, entre otros, proveedores del servicio de call y contact center, proveedores del servicio de mensajer\u00eda, empresas de cobranza y profesionales del derecho que colaboran con la entidad en la recuperaci\u00f3n de su cartera, proveedores de servicios de publicidad y mercadeo<\/li>\n\n\n\n<li>k. En todo caso, esas entidades estar\u00e1n igualmente sujetas a las mismas obligaciones de confidencialidad en el manejo de la informaci\u00f3n a que est\u00e1 sujeto&nbsp;<strong>RAYO<\/strong>&nbsp;con las limitaciones legales impuestas por las leyes aplicables sobre la materia, en la jurisdicci\u00f3n donde \u00e9sta se recolecte, archive, procese o transmita<\/li>\n<\/ol>\n\n\n\n<p>5. Finalidades comunes a todos los titulares de la informaci\u00f3n<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>a. Dar cumplimiento a las obligaciones legales de informaci\u00f3n a los entes administrativos, as\u00ed como a autoridades competentes que as\u00ed lo requieran<\/li>\n\n\n\n<li>b. Atender y dar tr\u00e1mite a las peticiones, quejas y reclamos formulados por los titulares de la informaci\u00f3n<\/li>\n\n\n\n<li>c. Conservarla para fines de control, estad\u00edsticos e hist\u00f3ricos, y\/o para cumplir con las obligaciones legales en lo que a conservaci\u00f3n de informaci\u00f3n y archivos se refiere<\/li>\n\n\n\n<li>d. Controlar el acceso y la seguridad de las instalaciones de RAYO y archivos almacenados en ellas mediante sistema de video vigilancia<\/li>\n<\/ol>\n\n\n\n<p>La informaci\u00f3n personal no ser\u00e1 utilizada o tratada con prop\u00f3sitos diferentes a los aqu\u00ed indicados. En todo caso,&nbsp;<strong>RAYO<\/strong>&nbsp;informar\u00e1 las finalidades espec\u00edficas al titular, de forma previa, expresa e informada al tratamiento de la informaci\u00f3n personal por parte de la entidad y la respectiva autorizaci\u00f3n por parte del titular.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">VI. Derechos de los titulares de la informaci\u00f3n y su ejercicio<\/h3>\n\n\n\n<p>Los titulares de los datos personales tratados por&nbsp;<strong>RAYO<\/strong>&nbsp;tienen derecho a:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Conocer, actualizar y rectificar sus datos personales. Este derecho se podr\u00e1 ejercer, entre otros frente a datos parciales, inexactos, incompletos, fraccionados, que induzcan a error, o aquellos cuyo tratamiento est\u00e9 expresamente prohibido o no haya sido autorizado.<\/li>\n\n\n\n<li>Solicitar prueba de la autorizaci\u00f3n otorgada para el tratamiento, salvo cuando expresamente se except\u00fae como requisito la solicitud de la autorizaci\u00f3n al Titular, conforme a las normas vigentes.<\/li>\n\n\n\n<li>Ser informados, previa solicitud, respecto del uso que se le ha dado a sus datos personales.<\/li>\n\n\n\n<li>Revocar la autorizaci\u00f3n y\/o solicitar la supresi\u00f3n del dato cuando en el tratamiento no se respeten los principios, derechos y garant\u00edas constitucionales y legales. Sin embargo, tal revocatoria o la eliminaci\u00f3n de la informaci\u00f3n no ser\u00e1 procedente mientras se mantenga una relaci\u00f3n de tipo comercial o legal con&nbsp;<strong>RAYO<\/strong>.<\/li>\n\n\n\n<li>Acceder en forma gratuita a los datos personales que hayan sido objeto de tratamiento una vez al mes o cada vez que existan modificaciones sustanciales a estas pol\u00edticas de tratamiento de la informaci\u00f3n personal que motiven nuevas consultas.<\/li>\n<\/ol>\n\n\n\n<p>Para el ejercicio de estos derechos, el Titular podr\u00e1 contactarse con RAYO a trav\u00e9s de comunicaci\u00f3n escrita dirigida a nuestra \u00e1rea de atenci\u00f3n al cliente, a la siguiente direcci\u00f3n domicilio avenida 1era calle 7, edificio Omni, local Rayo, San Jos\u00e9, Costa Rica o al correo electr\u00f3nico:&nbsp;info@rayo.cr.<\/p>\n\n\n\n<p>Dicha comunicaci\u00f3n deber\u00e1 contener todos los datos del peticionario que sean necesarios para efectos de garantizar la oportuna y efectiva respuesta, acompa\u00f1ada de una descripci\u00f3n precisa de los datos personales respecto de los cuales el titular busca ejercer alguno de sus derechos.<\/p>\n\n\n\n<p>Es de anotar que la solicitud de eliminaci\u00f3n de los datos significar\u00e1 que los mismos no podr\u00e1n ser accesibles para el desarrollo de las operaciones normales de la entidad, sin embargo, podr\u00e1n mantenerse en sus archivos con fines estad\u00edsticos, hist\u00f3ricos, atenci\u00f3n de peticiones, quejas o reclamos presentados por el Titular o requerimiento de autoridades administrativas o judiciales en ejercicio de sus funciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">VII. Atenci\u00f3n de peticiones, consultas y reclamos<\/h3>\n\n\n\n<p><strong>RAYO<\/strong>, a trav\u00e9s de su \u00e1rea de atenci\u00f3n al cliente atender\u00e1 todas las peticiones, consultas, quejas y\/o reclamos del Titular de la informaci\u00f3n, relacionadas con los derechos de los titulares de la informaci\u00f3n.<\/p>\n\n\n\n<p>Las consultas ser\u00e1n atendidas en un t\u00e9rmino m\u00e1ximo de diez (10) d\u00edas h\u00e1biles contados a partir de la fecha de recibo de las mismas. Cuando no fuere posible atender una consulta dentro de dicho t\u00e9rmino, se informar\u00e1 al interesado, expresando los motivos de la demora y se\u00f1alando la fecha en que se atender\u00e1, bajo el entendido de que en ning\u00fan caso podr\u00e1 superar los cinco (5) d\u00edas h\u00e1biles siguientes al vencimiento del primer t\u00e9rmino.<\/p>\n\n\n\n<p>Cuando el Titular o sus causahabientes consideren que la informaci\u00f3n contenida en una base de datos debe ser objeto de correcci\u00f3n, actualizaci\u00f3n o supresi\u00f3n, o cuando adviertan el presunto incumplimiento de cualquiera de los deberes contenidos en la ley, podr\u00e1n presentar un reclamo ante el Responsable o Encargado del Tratamiento.<\/p>\n\n\n\n<p>Ante&nbsp;<strong>RAYO<\/strong>&nbsp;el reclamo se formular\u00e1 mediante solicitud dirigida a la entidad, con la identificaci\u00f3n del Titular, la descripci\u00f3n de los hechos que dan lugar al reclamo, la direcci\u00f3n y acompa\u00f1ando los documentos que se quiera hacer valer. Si el reclamo resulta incompleto, se requerir\u00e1 al interesado dentro de los cinco (5) d\u00edas h\u00e1biles siguientes a la recepci\u00f3n del reclamo para que subsane las fallas.<\/p>\n\n\n\n<p>Una vez sea recibido el reclamo, se incluir\u00e1 en la base de datos una leyenda que diga &#8220;reclamo en tr\u00e1mite&#8221;, en un t\u00e9rmino no mayor a dos (3) d\u00edas h\u00e1biles. Dicha leyenda deber\u00e1 mantenerse hasta que el reclamo sea decidido.<\/p>\n\n\n\n<p>Transcurridos dos (2) meses desde la fecha del requerimiento, sin que el solicitante presente la informaci\u00f3n requerida, en caso de reclamos incompletos, se entender\u00e1 que ha desistido del reclamo.<\/p>\n\n\n\n<p>En el evento en que&nbsp;<strong>RAYO<\/strong>&nbsp;no sea competente para resolver el reclamo, dar\u00e1 traslado a quien corresponda en un t\u00e9rmino m\u00e1ximo de dos (3) d\u00edas h\u00e1biles e informar\u00e1 de la situaci\u00f3n al interesado.<\/p>\n\n\n\n<p>En todo caso, el t\u00e9rmino m\u00e1ximo para atender el reclamo ser\u00e1 de quince (15) d\u00edas h\u00e1biles contados a partir del d\u00eda siguiente a la fecha de su recibo. Cuando no fuere posible atender el reclamo dentro de dicho t\u00e9rmino, se informar\u00e1 al interesado los motivos de la demora y la fecha en que se atender\u00e1 su reclamo, la cual en ning\u00fan caso podr\u00e1 superar los ocho (8) d\u00edas h\u00e1biles siguientes al vencimiento del primer t\u00e9rmino.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">VIII. Veracidad<\/h3>\n\n\n\n<p><strong>RAYO<\/strong>&nbsp;asumir\u00e1 que la informaci\u00f3n entregada por sus clientes, usuarios, solicitantes de servicios, funcionarios y proveedores es completa, actual y veraz, resultando de su entera responsabilidad cualquier disconformidad entre los datos entregados y la realidad.<\/p>\n\n\n\n<p>Los Titulares de datos personales se encuentran comprometidos a notificarnos de cualquier cambio en la informaci\u00f3n suministrada a&nbsp;<strong>RAYO<\/strong>&nbsp;por cualquier medio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">IX. Obligaciones de Rayo como responsable del tratamiento<\/h3>\n\n\n\n<p><strong>RAYO<\/strong>, en su calidad de Responsable del Tratamiento cumple con las siguientes obligaciones, sin perjuicio de las dem\u00e1s disposiciones previstas en la Ley 1581 de 2012 y\/o en otras normas que rijan su actividad:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Garantizar al Titular, en todo tiempo, el pleno y efectivo ejercicio del derecho de h\u00e1beas data.<\/li>\n\n\n\n<li>Solicitar y conservar, en las condiciones previstas en la ley, copia de la respectiva autorizaci\u00f3n otorgada por el Titular en los casos en que resulte necesario.<\/li>\n\n\n\n<li>Informar debidamente al Titular sobre la finalidad de la recolecci\u00f3n y los derechos que le asisten por virtud de la autorizaci\u00f3n otorgada en los casos en que resulte necesario.<\/li>\n\n\n\n<li>Conservar la informaci\u00f3n bajo las condiciones de seguridad necesarias para impedir su adulteraci\u00f3n, p\u00e9rdida, consulta, uso o acceso no autorizado o fraudulento por parte de terceros.<\/li>\n\n\n\n<li>Garantizar que la informaci\u00f3n que se suministre al Encargado del Tratamiento sea veraz, completa, exacta, actualizada, comprobable y comprensible.<\/li>\n\n\n\n<li>Actualizar la informaci\u00f3n, comunicando de forma oportuna al Encargado del Tratamiento, todas las novedades respecto de los datos que previamente le haya suministrado y adoptar las dem\u00e1s medidas necesarias para que la informaci\u00f3n suministrada a este se mantenga actualizada.<\/li>\n\n\n\n<li>Rectificar la informaci\u00f3n cuando sea incorrecta y comunicar lo pertinente al Encargado del Tratamiento.<\/li>\n\n\n\n<li>Exigir al Encargado del Tratamiento en todo momento, el respeto a las condiciones de seguridad y privacidad de la informaci\u00f3n del Titular.<\/li>\n\n\n\n<li>Tramitar las consultas y reclamos formulados en los t\u00e9rminos se\u00f1alados en la ley.<\/li>\n\n\n\n<li>Adoptar un manual interno de pol\u00edticas y procedimientos para garantizar el adecuado cumplimiento de la ley y en especial, para la atenci\u00f3n de consultas y reclamos.<\/li>\n\n\n\n<li>Informar a la autoridad de protecci\u00f3n de datos cuando se presenten violaciones a los c\u00f3digos de seguridad y existan riesgos en la administraci\u00f3n de la informaci\u00f3n de los Titulares.<\/li>\n\n\n\n<li>Cumplir las instrucciones y requerimientos que imparta la Superintendencia de Industria y Comercio.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">X. Modificaciones a la pol\u00edtica de privacidad<\/h3>\n\n\n\n<p><strong>RAYO<\/strong>&nbsp;se reserva el derecho de modificar la presente pol\u00edtica de privacidad en cualquier momento y de manera unilateral. Para el efecto realizar\u00e1 la publicaci\u00f3n de un aviso en la p\u00e1gina de internet con diez (10) d\u00edas h\u00e1biles de antelaci\u00f3n a su entrada en vigencia. En caso de no estar de acuerdo por razones v\u00e1lidas y que se constituyan en una justa causa con las nuevas pol\u00edticas de manejo de la informaci\u00f3n personal, los Titulares de la informaci\u00f3n o sus representantes podr\u00e1n solicitar a&nbsp;<strong>RAYO<\/strong>&nbsp;el retiro de su informaci\u00f3n a trav\u00e9s del medio indicado anteriormente, sin embargo, no se podr\u00e1 solicitar el retiro de los datos mientras se mantenga un v\u00ednculo de cualquier orden con&nbsp;<strong>RAYO<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">XI. Autorizaci\u00f3n para el tratamiento de datos personales<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Los datos suministrados por el Titular ser\u00e1n tratados para los siguientes prop\u00f3sitos: (i) con fines contractuales, (ii) con fines de comercializaci\u00f3n y promoci\u00f3n, (iii) para actualizar datos y brindar informaci\u00f3n relevante, (iv) para asegurar y prestar el servicio de atenci\u00f3n al&nbsp;<strong>USUARIO<\/strong>, (v) con fines de informaci\u00f3n, en la utilizaci\u00f3n del producto, la venta o entrega del producto, (vi) con fines de cobro.<\/li>\n\n\n\n<li>El&nbsp;<strong>USUARIO<\/strong>&nbsp;autoriza a&nbsp;<strong>RAYO<\/strong>&nbsp;a transferir o transmitir los datos personales a su productor o proveedor, comercios, empresas y\/o entidades afiliadas o aliados comerciales con los que se haya pactado un acuerdo de transferencia de datos, ya sean transferidos en territorio costarricense o en el extranjero.<\/li>\n\n\n\n<li>El&nbsp;<strong>USUARIO<\/strong>&nbsp;como titular de los datos personales tiene derecho a conocer, actualizar, rectificar o suprimir su informaci\u00f3n, as\u00ed como revocar la presente autorizaci\u00f3n. Estos derechos pueden ser ejercidos seg\u00fan el mecanismo establecido en la Pol\u00edtica de Protecci\u00f3n de Tratamiento de Datos Personales. El&nbsp;<strong>USUARIO<\/strong>&nbsp;tiene derecho a acudir a la Superintendencia de Industria y Comercio para presentar quejas sobre cualquier irregularidad respecto a la aplicaci\u00f3n de la Pol\u00edtica de protecci\u00f3n y Datos Personales.<\/li>\n\n\n\n<li>En caso de suministrar datos personales de terceros, el&nbsp;<strong>USUARIO<\/strong>&nbsp;declara que los ha suministrado con la autorizaci\u00f3n expresa del titular.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>RayoCR S.A.&nbsp;(en adelante&nbsp;\u201cRAYO\u201d) es una sociedad costarricense identificada con el Ceb Jur\u00eddico n\u00famero 3-101-673923, cuyo domicilio es Avenida 1era calle 7, edificio Omni, local Rayo, San Jos\u00e9, Costa Rica. En cumplimiento de lo dictado en Ley N\u00ba 8968 del 2011 de la Constituci\u00f3n Pol\u00edtica y sus decretos reglamentarios se informa que&nbsp;RAYO&nbsp;es Responsable del Tratamiento de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":7,"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1807,"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/pages\/3\/revisions\/1807"}],"wp:attachment":[{"href":"https:\/\/rayocredit.com\/cr\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}